{"id":4821,"date":"2026-09-01T15:53:38","date_gmt":"2026-09-01T15:53:38","guid":{"rendered":"https:\/\/elprogresivo.mx\/index.php\/2026\/09\/01\/estudiantes-crean-app-para-donar-sangre-en-queretaro\/"},"modified":"2026-09-01T15:53:38","modified_gmt":"2026-09-01T15:53:38","slug":"estudiantes-crean-app-para-donar-sangre-en-queretaro","status":"publish","type":"post","link":"https:\/\/elprogresivo.mx\/index.php\/2026\/09\/01\/estudiantes-crean-app-para-donar-sangre-en-queretaro\/","title":{"rendered":"Estudiantes crean app para donar sangre en Quer\u00e9taro"},"content":{"rendered":"<p>Ya no hace falta hacer largas filas en el Hospital General de San Juan del R\u00edo para donar sangre. Estudiantes de la Universidad Tecnol\u00f3gica de San Juan del R\u00edo (UT San Juan) lanzaron &#8220;Latido Rojo&#8221;, una plataforma que permite agendar citas directamente por WhatsApp.<\/p>\n<p>Los alumnos de sexto cuatrimestre de Tecnolog\u00edas de la Informaci\u00f3n construyeron esta herramienta para simplificar el tr\u00e1mite. El sistema genera comprobantes digitales y automatiza los papeleos administrativos que antes tomaban tiempo en ventanilla.<\/p>\n<p>El rector de la universidad, Fernando Ferrusca, explic\u00f3 el problema que buscan resolver con este proyecto. &#8220;Detr\u00e1s de cada donaci\u00f3n de sangre, existen personas que vienen de lugares lejanos, que tienen que pedir permiso en su trabajo o tomar horas de su negocio, para abrir la posibilidad de salvar una vida. Por eso contribuir a que el tr\u00e1mite sea m\u00e1s \u00e1gil, accesible, ordenado y eficiente para el donador, representa verdaderamente pensar en las personas&#8221;, puntualiz\u00f3.<\/p>\n<p>La secretaria de Salud, Martina P\u00e9rez Rend\u00f3n, agradeci\u00f3 la iniciativa. Se\u00f1al\u00f3 que la tecnolog\u00eda se convierte en un aliado pr\u00e1ctico para la atenci\u00f3n m\u00e9dica y reconoci\u00f3 el esfuerzo de los j\u00f3venes por aplicar sus conocimientos a favor de la comunidad.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ya no hace falta hacer largas filas en el Hospital General de San Juan del&#8230;<\/p>\n","protected":false},"author":5,"featured_media":4820,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[1],"tags":[876,1318,205,3227,1140],"class_list":["post-4821","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog","tag-300-anos-acueducto-queretaro-el-marques","tag-biotecnologia","tag-casas-de-salud-corregidora","tag-donacion-de-sangre","tag-ut-san-juan"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Ya no hace falta hacer largas filas en el Hospital General de San Juan del R\u00edo para donar sangre. Estudiantes de la Universidad Tecnol\u00f3gica de San Juan del R\u00edo (UT San Juan) lanzaron &quot;Latido Rojo&quot;, una plataforma que permite agendar citas directamente por WhatsApp. Los alumnos de sexto cuatrimestre de Tecnolog\u00edas de la Informaci\u00f3n construyeron\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Staff\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/elprogresivo.mx\/index.php\/2026\/09\/01\/estudiantes-crean-app-para-donar-sangre-en-queretaro\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_MX\" \/>\n\t\t<meta property=\"og:site_name\" content=\"elprogresivo.mx - Construimos una nueva etapa en informaci\u00f3n\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Estudiantes crean app para donar sangre en Quer\u00e9taro - elprogresivo.mx\" \/>\n\t\t<meta property=\"og:description\" content=\"Ya no hace falta hacer largas filas en el Hospital General de San Juan del R\u00edo para donar sangre. Estudiantes de la Universidad Tecnol\u00f3gica de San Juan del R\u00edo (UT San Juan) lanzaron &quot;Latido Rojo&quot;, una plataforma que permite agendar citas directamente por WhatsApp. Los alumnos de sexto cuatrimestre de Tecnolog\u00edas de la Informaci\u00f3n construyeron\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/elprogresivo.mx\/index.php\/2026\/09\/01\/estudiantes-crean-app-para-donar-sangre-en-queretaro\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/elprogresivo.mx\/wp-content\/uploads\/2024\/02\/cropped-LogoBlanco.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/elprogresivo.mx\/wp-content\/uploads\/2024\/02\/cropped-LogoBlanco.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2026-09-01T15:53:38+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2026-09-01T15:53:38+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Estudiantes crean app para donar sangre en Quer\u00e9taro - elprogresivo.mx\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Ya no hace falta hacer largas filas en el Hospital General de San Juan del R\u00edo para donar sangre. Estudiantes de la Universidad Tecnol\u00f3gica de San Juan del R\u00edo (UT San Juan) lanzaron &quot;Latido Rojo&quot;, una plataforma que permite agendar citas directamente por WhatsApp. Los alumnos de sexto cuatrimestre de Tecnolog\u00edas de la Informaci\u00f3n construyeron\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/elprogresivo.mx\/wp-content\/uploads\/2024\/02\/cropped-LogoBlanco.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/elprogresivo.mx\\\/index.php\\\/2026\\\/09\\\/01\\\/estudiantes-crean-app-para-donar-sangre-en-queretaro\\\/#blogposting\",\"name\":\"Estudiantes crean app para donar sangre en Quer\\u00e9taro - elprogresivo.mx\",\"headline\":\"Estudiantes crean app para donar sangre en Quer\\u00e9taro\",\"author\":{\"@id\":\"https:\\\/\\\/elprogresivo.mx\\\/index.php\\\/author\\\/emmanuel-galvan\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/elprogresivo.mx\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/elprogresivo.mx\\\/wp-content\\\/uploads\\\/2026\\\/09\\\/noticia_20260901095323-scaled.jpg\",\"width\":2560,\"height\":1545},\"datePublished\":\"2026-09-01T15:53:38+00:00\",\"dateModified\":\"2026-09-01T15:53:38+00:00\",\"inLanguage\":\"es-MX\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/elprogresivo.mx\\\/index.php\\\/2026\\\/09\\\/01\\\/estudiantes-crean-app-para-donar-sangre-en-queretaro\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/elprogresivo.mx\\\/index.php\\\/2026\\\/09\\\/01\\\/estudiantes-crean-app-para-donar-sangre-en-queretaro\\\/#webpage\"},\"articleSection\":\"Blog, 300 a\\u00f1os Acueducto Quer\\u00e9taro El Marqu\\u00e9s, Biotecnolog\\u00eda, Casas de Salud Corregidora, Donaci\\u00f3n de sangre, UT San Juan\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/elprogresivo.mx\\\/index.php\\\/2026\\\/09\\\/01\\\/estudiantes-crean-app-para-donar-sangre-en-queretaro\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/elprogresivo.mx#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/elprogresivo.mx\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/elprogresivo.mx\\\/index.php\\\/category\\\/blog\\\/#listItem\",\"name\":\"Blog\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/elprogresivo.mx\\\/index.php\\\/category\\\/blog\\\/#listItem\",\"position\":2,\"name\":\"Blog\",\"item\":\"https:\\\/\\\/elprogresivo.mx\\\/index.php\\\/category\\\/blog\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/elprogresivo.mx\\\/index.php\\\/2026\\\/09\\\/01\\\/estudiantes-crean-app-para-donar-sangre-en-queretaro\\\/#listItem\",\"name\":\"Estudiantes crean app para donar sangre en Quer\\u00e9taro\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/elprogresivo.mx#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/elprogresivo.mx\\\/index.php\\\/2026\\\/09\\\/01\\\/estudiantes-crean-app-para-donar-sangre-en-queretaro\\\/#listItem\",\"position\":3,\"name\":\"Estudiantes crean app para donar sangre en Quer\\u00e9taro\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/elprogresivo.mx\\\/index.php\\\/category\\\/blog\\\/#listItem\",\"name\":\"Blog\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/elprogresivo.mx\\\/#organization\",\"name\":\"elprogresivo.mx\",\"description\":\"Construimos una nueva etapa en informaci\\u00f3n\",\"url\":\"https:\\\/\\\/elprogresivo.mx\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/elprogresivo.mx\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/cropped-LogoBlanco.png\",\"@id\":\"https:\\\/\\\/elprogresivo.mx\\\/index.php\\\/2026\\\/09\\\/01\\\/estudiantes-crean-app-para-donar-sangre-en-queretaro\\\/#organizationLogo\",\"width\":2096,\"height\":332},\"image\":{\"@id\":\"https:\\\/\\\/elprogresivo.mx\\\/index.php\\\/2026\\\/09\\\/01\\\/estudiantes-crean-app-para-donar-sangre-en-queretaro\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/elprogresivo.mx\\\/index.php\\\/author\\\/emmanuel-galvan\\\/#author\",\"url\":\"https:\\\/\\\/elprogresivo.mx\\\/index.php\\\/author\\\/emmanuel-galvan\\\/\",\"name\":\"Staff\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/elprogresivo.mx\\\/index.php\\\/2026\\\/09\\\/01\\\/estudiantes-crean-app-para-donar-sangre-en-queretaro\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3bb87242634c3adf910515f41e6e392ab758b98c8ee7fd12a54fcb5270441486?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Staff\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/elprogresivo.mx\\\/index.php\\\/2026\\\/09\\\/01\\\/estudiantes-crean-app-para-donar-sangre-en-queretaro\\\/#webpage\",\"url\":\"https:\\\/\\\/elprogresivo.mx\\\/index.php\\\/2026\\\/09\\\/01\\\/estudiantes-crean-app-para-donar-sangre-en-queretaro\\\/\",\"name\":\"Estudiantes crean app para donar sangre en Quer\\u00e9taro - elprogresivo.mx\",\"description\":\"Ya no hace falta hacer largas filas en el Hospital General de San Juan del R\\u00edo para donar sangre. Estudiantes de la Universidad Tecnol\\u00f3gica de San Juan del R\\u00edo (UT San Juan) lanzaron \\\"Latido Rojo\\\", una plataforma que permite agendar citas directamente por WhatsApp. Los alumnos de sexto cuatrimestre de Tecnolog\\u00edas de la Informaci\\u00f3n construyeron\",\"inLanguage\":\"es-MX\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/elprogresivo.mx\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/elprogresivo.mx\\\/index.php\\\/2026\\\/09\\\/01\\\/estudiantes-crean-app-para-donar-sangre-en-queretaro\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/elprogresivo.mx\\\/index.php\\\/author\\\/emmanuel-galvan\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/elprogresivo.mx\\\/index.php\\\/author\\\/emmanuel-galvan\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/elprogresivo.mx\\\/wp-content\\\/uploads\\\/2026\\\/09\\\/noticia_20260901095323-scaled.jpg\",\"@id\":\"https:\\\/\\\/elprogresivo.mx\\\/index.php\\\/2026\\\/09\\\/01\\\/estudiantes-crean-app-para-donar-sangre-en-queretaro\\\/#mainImage\",\"width\":2560,\"height\":1545},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/elprogresivo.mx\\\/index.php\\\/2026\\\/09\\\/01\\\/estudiantes-crean-app-para-donar-sangre-en-queretaro\\\/#mainImage\"},\"datePublished\":\"2026-09-01T15:53:38+00:00\",\"dateModified\":\"2026-09-01T15:53:38+00:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/elprogresivo.mx\\\/#website\",\"url\":\"https:\\\/\\\/elprogresivo.mx\\\/\",\"name\":\"elprogresivo.mx\",\"description\":\"Construimos una nueva etapa en informaci\\u00f3n\",\"inLanguage\":\"es-MX\",\"publisher\":{\"@id\":\"https:\\\/\\\/elprogresivo.mx\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Estudiantes crean app para donar sangre en Quer\u00e9taro - elprogresivo.mx","description":"Ya no hace falta hacer largas filas en el Hospital General de San Juan del R\u00edo para donar sangre. Estudiantes de la Universidad Tecnol\u00f3gica de San Juan del R\u00edo (UT San Juan) lanzaron \"Latido Rojo\", una plataforma que permite agendar citas directamente por WhatsApp. Los alumnos de sexto cuatrimestre de Tecnolog\u00edas de la Informaci\u00f3n construyeron","canonical_url":"https:\/\/elprogresivo.mx\/index.php\/2026\/09\/01\/estudiantes-crean-app-para-donar-sangre-en-queretaro\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/elprogresivo.mx\/index.php\/2026\/09\/01\/estudiantes-crean-app-para-donar-sangre-en-queretaro\/#blogposting","name":"Estudiantes crean app para donar sangre en Quer\u00e9taro - elprogresivo.mx","headline":"Estudiantes crean app para donar sangre en Quer\u00e9taro","author":{"@id":"https:\/\/elprogresivo.mx\/index.php\/author\/emmanuel-galvan\/#author"},"publisher":{"@id":"https:\/\/elprogresivo.mx\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/elprogresivo.mx\/wp-content\/uploads\/2026\/09\/noticia_20260901095323-scaled.jpg","width":2560,"height":1545},"datePublished":"2026-09-01T15:53:38+00:00","dateModified":"2026-09-01T15:53:38+00:00","inLanguage":"es-MX","mainEntityOfPage":{"@id":"https:\/\/elprogresivo.mx\/index.php\/2026\/09\/01\/estudiantes-crean-app-para-donar-sangre-en-queretaro\/#webpage"},"isPartOf":{"@id":"https:\/\/elprogresivo.mx\/index.php\/2026\/09\/01\/estudiantes-crean-app-para-donar-sangre-en-queretaro\/#webpage"},"articleSection":"Blog, 300 a\u00f1os Acueducto Quer\u00e9taro El Marqu\u00e9s, Biotecnolog\u00eda, Casas de Salud Corregidora, Donaci\u00f3n de sangre, UT San Juan"},{"@type":"BreadcrumbList","@id":"https:\/\/elprogresivo.mx\/index.php\/2026\/09\/01\/estudiantes-crean-app-para-donar-sangre-en-queretaro\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/elprogresivo.mx#listItem","position":1,"name":"Home","item":"https:\/\/elprogresivo.mx","nextItem":{"@type":"ListItem","@id":"https:\/\/elprogresivo.mx\/index.php\/category\/blog\/#listItem","name":"Blog"}},{"@type":"ListItem","@id":"https:\/\/elprogresivo.mx\/index.php\/category\/blog\/#listItem","position":2,"name":"Blog","item":"https:\/\/elprogresivo.mx\/index.php\/category\/blog\/","nextItem":{"@type":"ListItem","@id":"https:\/\/elprogresivo.mx\/index.php\/2026\/09\/01\/estudiantes-crean-app-para-donar-sangre-en-queretaro\/#listItem","name":"Estudiantes crean app para donar sangre en Quer\u00e9taro"},"previousItem":{"@type":"ListItem","@id":"https:\/\/elprogresivo.mx#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/elprogresivo.mx\/index.php\/2026\/09\/01\/estudiantes-crean-app-para-donar-sangre-en-queretaro\/#listItem","position":3,"name":"Estudiantes crean app para donar sangre en Quer\u00e9taro","previousItem":{"@type":"ListItem","@id":"https:\/\/elprogresivo.mx\/index.php\/category\/blog\/#listItem","name":"Blog"}}]},{"@type":"Organization","@id":"https:\/\/elprogresivo.mx\/#organization","name":"elprogresivo.mx","description":"Construimos una nueva etapa en informaci\u00f3n","url":"https:\/\/elprogresivo.mx\/","logo":{"@type":"ImageObject","url":"https:\/\/elprogresivo.mx\/wp-content\/uploads\/2024\/02\/cropped-LogoBlanco.png","@id":"https:\/\/elprogresivo.mx\/index.php\/2026\/09\/01\/estudiantes-crean-app-para-donar-sangre-en-queretaro\/#organizationLogo","width":2096,"height":332},"image":{"@id":"https:\/\/elprogresivo.mx\/index.php\/2026\/09\/01\/estudiantes-crean-app-para-donar-sangre-en-queretaro\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/elprogresivo.mx\/index.php\/author\/emmanuel-galvan\/#author","url":"https:\/\/elprogresivo.mx\/index.php\/author\/emmanuel-galvan\/","name":"Staff","image":{"@type":"ImageObject","@id":"https:\/\/elprogresivo.mx\/index.php\/2026\/09\/01\/estudiantes-crean-app-para-donar-sangre-en-queretaro\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/3bb87242634c3adf910515f41e6e392ab758b98c8ee7fd12a54fcb5270441486?s=96&d=mm&r=g","width":96,"height":96,"caption":"Staff"}},{"@type":"WebPage","@id":"https:\/\/elprogresivo.mx\/index.php\/2026\/09\/01\/estudiantes-crean-app-para-donar-sangre-en-queretaro\/#webpage","url":"https:\/\/elprogresivo.mx\/index.php\/2026\/09\/01\/estudiantes-crean-app-para-donar-sangre-en-queretaro\/","name":"Estudiantes crean app para donar sangre en Quer\u00e9taro - elprogresivo.mx","description":"Ya no hace falta hacer largas filas en el Hospital General de San Juan del R\u00edo para donar sangre. Estudiantes de la Universidad Tecnol\u00f3gica de San Juan del R\u00edo (UT San Juan) lanzaron \"Latido Rojo\", una plataforma que permite agendar citas directamente por WhatsApp. Los alumnos de sexto cuatrimestre de Tecnolog\u00edas de la Informaci\u00f3n construyeron","inLanguage":"es-MX","isPartOf":{"@id":"https:\/\/elprogresivo.mx\/#website"},"breadcrumb":{"@id":"https:\/\/elprogresivo.mx\/index.php\/2026\/09\/01\/estudiantes-crean-app-para-donar-sangre-en-queretaro\/#breadcrumblist"},"author":{"@id":"https:\/\/elprogresivo.mx\/index.php\/author\/emmanuel-galvan\/#author"},"creator":{"@id":"https:\/\/elprogresivo.mx\/index.php\/author\/emmanuel-galvan\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/elprogresivo.mx\/wp-content\/uploads\/2026\/09\/noticia_20260901095323-scaled.jpg","@id":"https:\/\/elprogresivo.mx\/index.php\/2026\/09\/01\/estudiantes-crean-app-para-donar-sangre-en-queretaro\/#mainImage","width":2560,"height":1545},"primaryImageOfPage":{"@id":"https:\/\/elprogresivo.mx\/index.php\/2026\/09\/01\/estudiantes-crean-app-para-donar-sangre-en-queretaro\/#mainImage"},"datePublished":"2026-09-01T15:53:38+00:00","dateModified":"2026-09-01T15:53:38+00:00"},{"@type":"WebSite","@id":"https:\/\/elprogresivo.mx\/#website","url":"https:\/\/elprogresivo.mx\/","name":"elprogresivo.mx","description":"Construimos una nueva etapa en informaci\u00f3n","inLanguage":"es-MX","publisher":{"@id":"https:\/\/elprogresivo.mx\/#organization"}}]},"og:locale":"es_MX","og:site_name":"elprogresivo.mx - Construimos una nueva etapa en informaci\u00f3n","og:type":"article","og:title":"Estudiantes crean app para donar sangre en Quer\u00e9taro - elprogresivo.mx","og:description":"Ya no hace falta hacer largas filas en el Hospital General de San Juan del R\u00edo para donar sangre. Estudiantes de la Universidad Tecnol\u00f3gica de San Juan del R\u00edo (UT San Juan) lanzaron &quot;Latido Rojo&quot;, una plataforma que permite agendar citas directamente por WhatsApp. Los alumnos de sexto cuatrimestre de Tecnolog\u00edas de la Informaci\u00f3n construyeron","og:url":"https:\/\/elprogresivo.mx\/index.php\/2026\/09\/01\/estudiantes-crean-app-para-donar-sangre-en-queretaro\/","og:image":"https:\/\/elprogresivo.mx\/wp-content\/uploads\/2024\/02\/cropped-LogoBlanco.png","og:image:secure_url":"https:\/\/elprogresivo.mx\/wp-content\/uploads\/2024\/02\/cropped-LogoBlanco.png","article:published_time":"2026-09-01T15:53:38+00:00","article:modified_time":"2026-09-01T15:53:38+00:00","twitter:card":"summary_large_image","twitter:title":"Estudiantes crean app para donar sangre en Quer\u00e9taro - elprogresivo.mx","twitter:description":"Ya no hace falta hacer largas filas en el Hospital General de San Juan del R\u00edo para donar sangre. Estudiantes de la Universidad Tecnol\u00f3gica de San Juan del R\u00edo (UT San Juan) lanzaron &quot;Latido Rojo&quot;, una plataforma que permite agendar citas directamente por WhatsApp. Los alumnos de sexto cuatrimestre de Tecnolog\u00edas de la Informaci\u00f3n construyeron","twitter:image":"https:\/\/elprogresivo.mx\/wp-content\/uploads\/2024\/02\/cropped-LogoBlanco.png"},"aioseo_meta_data":{"post_id":"4821","title":null,"description":null,"keywords":null,"keyphrases":{"focus":[],"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"limit_modified_date":false,"created":"2026-09-01 15:59:27","updated":"2026-09-01 18:58:26","ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/elprogresivo.mx\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/elprogresivo.mx\/index.php\/category\/blog\/\" title=\"Blog\">Blog<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tEstudiantes crean app para donar sangre en Quer\u00e9taro\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/elprogresivo.mx"},{"label":"Blog","link":"https:\/\/elprogresivo.mx\/index.php\/category\/blog\/"},{"label":"Estudiantes crean app para donar sangre en Quer\u00e9taro","link":"https:\/\/elprogresivo.mx\/index.php\/2026\/09\/01\/estudiantes-crean-app-para-donar-sangre-en-queretaro\/"}],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/elprogresivo.mx\/index.php\/wp-json\/wp\/v2\/posts\/4821","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elprogresivo.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elprogresivo.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elprogresivo.mx\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/elprogresivo.mx\/index.php\/wp-json\/wp\/v2\/comments?post=4821"}],"version-history":[{"count":0,"href":"https:\/\/elprogresivo.mx\/index.php\/wp-json\/wp\/v2\/posts\/4821\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elprogresivo.mx\/index.php\/wp-json\/wp\/v2\/media\/4820"}],"wp:attachment":[{"href":"https:\/\/elprogresivo.mx\/index.php\/wp-json\/wp\/v2\/media?parent=4821"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elprogresivo.mx\/index.php\/wp-json\/wp\/v2\/categories?post=4821"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elprogresivo.mx\/index.php\/wp-json\/wp\/v2\/tags?post=4821"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}